{"id":13558,"date":"2023-12-11T18:53:04","date_gmt":"2023-12-11T17:53:04","guid":{"rendered":"https:\/\/www.rabelais32.org\/?p=13558"},"modified":"2023-12-11T21:00:30","modified_gmt":"2023-12-11T20:00:30","slug":"les-nouvelles-acquisitions-a-la-bibliotheque-decembre-2023","status":"publish","type":"post","link":"https:\/\/www.rabelais32.org\/index.php\/2023\/12\/11\/les-nouvelles-acquisitions-a-la-bibliotheque-decembre-2023\/","title":{"rendered":"Les nouvelles acquisitions de la biblioth\u00e8que : d\u00e9cembre 2023"},"content":{"rendered":"<p><a href=\"https:\/\/www.rabelais32.org\/wp-content\/uploads\/2022\/03\/logo-livres-good.png\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-11803 aligncenter\" src=\"https:\/\/www.rabelais32.org\/wp-content\/uploads\/2022\/03\/logo-livres-good-300x73.png\" alt=\"\" width=\"300\" height=\"73\" srcset=\"https:\/\/www.rabelais32.org\/wp-content\/uploads\/2022\/03\/logo-livres-good-300x73.png 300w, https:\/\/www.rabelais32.org\/wp-content\/uploads\/2022\/03\/logo-livres-good-768x186.png 768w, https:\/\/www.rabelais32.org\/wp-content\/uploads\/2022\/03\/logo-livres-good.png 940w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><strong><a href=\"https:\/\/www.rabelais32.org\/wp-content\/uploads\/2023\/12\/41soyuWaQbL._SY445_SX342_.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-13561 alignleft\" src=\"https:\/\/www.rabelais32.org\/wp-content\/uploads\/2023\/12\/41soyuWaQbL._SY445_SX342_-218x300.jpg\" alt=\"\" width=\"144\" height=\"198\" srcset=\"https:\/\/www.rabelais32.org\/wp-content\/uploads\/2023\/12\/41soyuWaQbL._SY445_SX342_-218x300.jpg 218w, https:\/\/www.rabelais32.org\/wp-content\/uploads\/2023\/12\/41soyuWaQbL._SY445_SX342_.jpg 323w\" sizes=\"auto, (max-width: 144px) 100vw, 144px\" \/><\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00a0\u00ab\u00a0Veiller sur elle \u00bb<\/strong> <strong>de Jean Baptiste ANDREA \u00a0\u00bb <\/strong><em><u>Prix Goncourt 2023 et Prix du Roman FNAC 2023<\/u><\/em><\/p>\n<p>Lente ascension d&rsquo;un sculpteur de g\u00e9nie.<\/p>\n<p>Mimo, un vieil homme se meurt dans un couvent en Italie. N&rsquo;\u00e9tant pas un religieux, il a souhait\u00e9 finir sa vie dans ce lieu pour \u00ab veiller sur elle \u00bb. N\u00e9 pauvre mais ayant de l&rsquo;or dans les mains, il est, tr\u00e8s jeune confi\u00e9 \u00e0 un de ses oncles qui est un sculpteur mais sans succ\u00e8s.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.rabelais32.org\/wp-content\/uploads\/2023\/12\/416OxgmirCL._SY445_SX342_.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-13565 alignleft\" src=\"https:\/\/www.rabelais32.org\/wp-content\/uploads\/2023\/12\/416OxgmirCL._SY445_SX342_-205x300.jpg\" alt=\"\" width=\"148\" height=\"216\" srcset=\"https:\/\/www.rabelais32.org\/wp-content\/uploads\/2023\/12\/416OxgmirCL._SY445_SX342_-205x300.jpg 205w, https:\/\/www.rabelais32.org\/wp-content\/uploads\/2023\/12\/416OxgmirCL._SY445_SX342_.jpg 304w\" sizes=\"auto, (max-width: 148px) 100vw, 148px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00ab\u00a0Triste tigre<\/strong> <strong>de Neige SINNO\u00a0\u00bb <\/strong><em><u>Prix Goncourt des lyc\u00e9ens et Prix Femina 2023<\/u><\/em><\/p>\n<p>Entre 7 et 14 ans, la petite Neige est viol\u00e9e r\u00e9guli\u00e8rement par son beau-p\u00e8re. La famille recompos\u00e9e vit dans les Alpes, dans les ann\u00e9es 90, et m\u00e8ne une vie de boh\u00e8me un peu marginale. En 2000, Neige et sa m\u00e8re portent plainte et l&rsquo;homme est condamn\u00e9, au terme d&rsquo;un proc\u00e8s, \u00e0 neuf ans de r\u00e9clusion.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.rabelais32.org\/wp-content\/uploads\/2023\/12\/91DAutBlF6L._SL1500_.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-13564 alignleft\" src=\"https:\/\/www.rabelais32.org\/wp-content\/uploads\/2023\/12\/91DAutBlF6L._SL1500_-204x300.jpg\" alt=\"\" width=\"148\" height=\"218\" srcset=\"https:\/\/www.rabelais32.org\/wp-content\/uploads\/2023\/12\/91DAutBlF6L._SL1500_-204x300.jpg 204w, https:\/\/www.rabelais32.org\/wp-content\/uploads\/2023\/12\/91DAutBlF6L._SL1500_-698x1024.jpg 698w, https:\/\/www.rabelais32.org\/wp-content\/uploads\/2023\/12\/91DAutBlF6L._SL1500_-768x1127.jpg 768w, https:\/\/www.rabelais32.org\/wp-content\/uploads\/2023\/12\/91DAutBlF6L._SL1500_.jpg 1022w\" sizes=\"auto, (max-width: 148px) 100vw, 148px\" \/><\/a><\/p>\n<p><strong>\u00ab\u00a0La Sentence \u00bb de Louise ERDRICH\u00a0\u00bb<\/strong>\u00a0 <em><u>Prix Femina \u00e9tranger 2023<\/u><\/em><\/p>\n<p>Tout d\u00e9marre en prison, apr\u00e8s un \u00ab crime \u00bb pour le moins \u00e9tonnant, puis la prisonni\u00e8re finit par \u00e9pouser son ge\u00f4lier \u2013 ou du moins le flic qui l\u2019a arr\u00eat\u00e9e.<br \/>\nElle se retrouve dans une librairie r\u00e9ellement hant\u00e9e par une ancienne cliente et o\u00f9 d\u00e9filent \u00e9galement de \u00ab dr\u00f4les \u00bb de clients.<\/p>\n<p>En toile de fond : une Am\u00e9rique elle aussi confront\u00e9e \u00e0 ses fant\u00f4mes r\u00e9els ou pr\u00e9sum\u00e9s\u00a0: le racisme, avec l\u2019\u00e9radication de la culture Am\u00e9rindienne et la mort de Georges Floyd, la maladie avec l\u2019arriv\u00e9e surprenante de l\u2019\u00e9pid\u00e9mie de Covid.<\/p>\n<p>La peur, la col\u00e8re, la haine, mais aussi beaucoup d\u2019amour et d&rsquo;amiti\u00e9.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.rabelais32.org\/wp-content\/uploads\/2023\/12\/71n6xOKwp0L._SL1500_.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-13562 alignleft\" src=\"https:\/\/www.rabelais32.org\/wp-content\/uploads\/2023\/12\/71n6xOKwp0L._SL1500_-195x300.jpg\" alt=\"\" width=\"156\" height=\"240\" srcset=\"https:\/\/www.rabelais32.org\/wp-content\/uploads\/2023\/12\/71n6xOKwp0L._SL1500_-195x300.jpg 195w, https:\/\/www.rabelais32.org\/wp-content\/uploads\/2023\/12\/71n6xOKwp0L._SL1500_-664x1024.jpg 664w, https:\/\/www.rabelais32.org\/wp-content\/uploads\/2023\/12\/71n6xOKwp0L._SL1500_-768x1184.jpg 768w, https:\/\/www.rabelais32.org\/wp-content\/uploads\/2023\/12\/71n6xOKwp0L._SL1500_.jpg 973w\" sizes=\"auto, (max-width: 156px) 100vw, 156px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00a0\u00ab\u00a0Un certain art de vivre\u00a0\u00bb<\/strong> <a href=\"https:\/\/www.google.fr\/search?hl=fr&amp;tbo=p&amp;tbm=bks&amp;q=inauthor:%22Dany+Laferri%C3%A8re%22\"><strong>Dany LAFERRIERE\u00a0 <\/strong>(de l\u2019Acad\u00e9mie Fran\u00e7aise)<strong>\u00a0\u00a0 <\/strong><\/a><\/p>\n<p>Voici l&rsquo;art de vivre de Dany Laferri\u00e8re. Sous forme de maximes, de r\u00e9flexions comment\u00e9es, de r\u00eaveries, cent pages pour devenir soi-m\u00eame un peu japonais.<\/p>\n<p>\u00ab J\u2019ai voulu savoir comment les choses s\u2019\u00e9taient pass\u00e9es dans cette vie o\u00f9 je n\u2019ai pas cess\u00e9 de bouger, souvent malgr\u00e9 moi. Toutes ces villes o\u00f9 j\u2019ai v\u00e9cu (Port-au-Prince, Petit-Go\u00e2ve, Montr\u00e9al, New-York, Miami, Paris, Tokyo), assez pour les int\u00e9grer en moi sans devenir s\u00e9dentaire pour autant. Je suis pass\u00e9, \u00e0 peine \u00e9tonn\u00e9, du sud au nord, du rhum au vin, de l\u2019\u00e9t\u00e9 \u00e0 l\u2019hiver, jusqu\u2019\u00e0 devenir un cerisier en fleur\u2026<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.rabelais32.org\/wp-content\/uploads\/2023\/12\/71YbP9Wj1TL._SL1500_.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-13563 alignleft\" src=\"https:\/\/www.rabelais32.org\/wp-content\/uploads\/2023\/12\/71YbP9Wj1TL._SL1500_-188x300.jpg\" alt=\"\" width=\"158\" height=\"252\" srcset=\"https:\/\/www.rabelais32.org\/wp-content\/uploads\/2023\/12\/71YbP9Wj1TL._SL1500_-188x300.jpg 188w, https:\/\/www.rabelais32.org\/wp-content\/uploads\/2023\/12\/71YbP9Wj1TL._SL1500_-643x1024.jpg 643w, https:\/\/www.rabelais32.org\/wp-content\/uploads\/2023\/12\/71YbP9Wj1TL._SL1500_-768x1223.jpg 768w, https:\/\/www.rabelais32.org\/wp-content\/uploads\/2023\/12\/71YbP9Wj1TL._SL1500_.jpg 942w\" sizes=\"auto, (max-width: 158px) 100vw, 158px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00a0\u00ab\u00a0Son odeur apr\u00e8s la pluie<\/strong>\u00a0\u00bb <strong>de C\u00e9dric SAPIN-DEFOUR<\/strong><\/p>\n<p>C\u2019est une histoire d\u2019amour, de vie et de mort. Sur quel autre tr\u00e9pied la litt\u00e9rature danse-t-elle depuis des si\u00e8cles ? Dans Son odeur apr\u00e8s la pluie, ce tr\u00e9pied, de surcro\u00eet, est instable car il unit deux \u00eatres n\u2019appartenant pas \u00e0 la m\u00eame esp\u00e8ce : un homme et son chien.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; \u00a0\u00ab\u00a0Veiller sur elle \u00bb de Jean Baptiste ANDREA \u00a0\u00bb Prix Goncourt 2023 et Prix du Roman FNAC 2023 Lente ascension d&rsquo;un sculpteur de g\u00e9nie. Mimo, un vieil homme se meurt dans un couvent en Italie. N&rsquo;\u00e9tant pas un religieux, &hellip; <a href=\"https:\/\/www.rabelais32.org\/index.php\/2023\/12\/11\/les-nouvelles-acquisitions-a-la-bibliotheque-decembre-2023\/\">Lire la suite\u00ad\u00ad<\/a><\/p>\n","protected":false},"author":1,"featured_media":13576,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19,22],"tags":[],"class_list":["post-13558","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-partager","category-bibliotheque"],"_links":{"self":[{"href":"https:\/\/www.rabelais32.org\/index.php\/wp-json\/wp\/v2\/posts\/13558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rabelais32.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rabelais32.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rabelais32.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rabelais32.org\/index.php\/wp-json\/wp\/v2\/comments?post=13558"}],"version-history":[{"count":9,"href":"https:\/\/www.rabelais32.org\/index.php\/wp-json\/wp\/v2\/posts\/13558\/revisions"}],"predecessor-version":[{"id":13582,"href":"https:\/\/www.rabelais32.org\/index.php\/wp-json\/wp\/v2\/posts\/13558\/revisions\/13582"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rabelais32.org\/index.php\/wp-json\/wp\/v2\/media\/13576"}],"wp:attachment":[{"href":"https:\/\/www.rabelais32.org\/index.php\/wp-json\/wp\/v2\/media?parent=13558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rabelais32.org\/index.php\/wp-json\/wp\/v2\/categories?post=13558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rabelais32.org\/index.php\/wp-json\/wp\/v2\/tags?post=13558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}